{"id":28995,"date":"2021-11-10T15:04:36","date_gmt":"2021-11-10T14:04:36","guid":{"rendered":"https:\/\/yourhappybox.ch\/?p=28995"},"modified":"2022-02-23T08:49:26","modified_gmt":"2022-02-23T07:49:26","slug":"vitamine-und-mineralien-alles-was-du-wissen-musst","status":"publish","type":"post","link":"https:\/\/yourhappybox.ch\/fr\/vitamine-und-mineralien-alles-was-du-wissen-musst\/","title":{"rendered":"Vit\u00adamine und Mi\u00adne\u00adra\u00adlien: Al\u00adles, was Du wis\u00adsen&nbsp;musst"},"content":{"rendered":"<div id=\"fws_6a57021d72559\" data-column-margin=\"default\" data-midnight=\"dark\" class=\"wpb_row vc_row-fluid vc_row\" style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\"><div class=\"row-bg viewport-desktop\" style><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color data-bg-opacity=\"1\" data-animation data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\">\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57021d734af\" data-midnight data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\" style><div class=\"row-bg-wrap\"> <div class=\"row-bg\"><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color data-bg-opacity=\"1\" data-animation data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\">\n\t<div class=\"wpb_wrapper\">\n\t\t<h3>Fols\u00e4ure<\/h3>\n<p>Es gibt wohl we\u00adnige Vit\u00adamine, \u00fcber die zum Thema Schwan\u00adger\u00adschaft mehr dis\u00adku\u00adtiert wird als Fol\u00ads\u00e4ure. Wir ha\u00adben f\u00fcr Dich das Wich\u00adtigste zusammengefasst.<\/p>\n<p>Frau\u00aden\u00ad\u00e4rzte und \u2011arzt\u00adin\u00adnen ra\u00adten Frauen mit Kin\u00adder\u00adwunsch, pro\u00adphy\u00adlak\u00adtisch Fol\u00ads\u00e4ure-Pr\u00e4\u00adpa\u00adrate ein\u00adzu\u00adneh\u00admen. Die <a href=\"https:\/\/stiftung-folsaeure.ch\/de\/folsaeure-hilft\/schwangerschaft\/\">Stif\u00adtung Fol\u00ads\u00e4ure<\/a> spricht von drei Mo\u00adna\u00adten vor Schwan\u00adger\u00adschafts\u00adbe\u00adginn. Bis zur zw\u00f6lf\u00adten Schwan\u00adger\u00adschafts\u00adwo\u00adche soll\u00adten Frauen min\u00addes\u00adtens 400 Mi\u00adkro\u00adgramm zu\u00ads\u00e4tz\u00adlich an Fol\u00ads\u00e4ure pro Tag zu sich neh\u00admen. Durch diese Mass\u00adnahme, so das <a href=\"https:\/\/www.admin.ch\/gov\/de\/start\/dokumentation\/medienmitteilungen.msg-id-24967.html\">Bun\u00addes\u00adamt f\u00fcr Ge\u00adsund\u00adheit<\/a>, \u00abver\u00adrin\u00adgert sich das Ri\u00adsiko des Kin\u00addes f\u00fcr Neu\u00adr\u00adal\u00adrohr\u00adde\u00adfekte und an\u00addere Fehl\u00adbil\u00addun\u00adgen wie z.B. Lip\u00adpen-Kie\u00adfer-Gau\u00admen\u00adspal\u00adten oder Herzfehler\u00bb.<\/p>\n<p>Denn der Kon\u00adsum von Le\u00adbens\u00admit\u00adteln, die auf na\u00adt\u00fcr\u00adli\u00adche Weise reich an Fol\u00ads\u00e4ure sind, w\u00fcr\u00adden nicht aus\u00adrei\u00adchen, um dem Ri\u00adsiko ent\u00adge\u00adgen\u00adzu\u00adwir\u00adken. Aber sie ge\u00adh\u00f6\u00adren den\u00adnoch f\u00fcr eine aus\u00adge\u00adwo\u00adgene Er\u00adn\u00e4h\u00adrung un\u00adbe\u00addingt auf den Spei\u00adse\u00adplan: Fol\u00ads\u00e4u\u00adre\u00adlie\u00adfe\u00adran\u00adten sind bei\u00adspiels\u00adweise gr\u00fc\u00adnes Blatt\u00adge\u00adm\u00fcse wie Gr\u00fcn\u00adkohl oder Spi\u00adnat, aber auch H\u00fcl\u00adsen\u00adfr\u00fcchte, N\u00fcsse so\u00adwie Voll\u00adkorn\u00adpro\u00addukte. Bei der Fol\u00ads\u00e4ure han\u00addelt es sich \u00fcb\u00adri\u00adgens um Vit\u00adamin B9 und es ist es\u00adsen\u00adti\u00adell f\u00fcr Zell\u00adfunk\u00adtion und \u2011tei\u00adlung. Men\u00adschen k\u00f6n\u00adnen Fol\u00ads\u00e4ure nicht sel\u00adber her\u00adstel\u00adlen, son\u00addern neh\u00admen diese \u00fcber die Nah\u00adrung auf oder als Zu\u00adsatz in syn\u00adthe\u00adti\u00adscher&nbsp;Form.<\/p>\n<h3>Auf einen Blick: 12 weitere Vitamine f\u00fcr eine gesunde Schwangerschaft<\/h3>\n<table>\n<tbody>\n<tr>\n<td width=\"124\">Vit\u00adamin<\/td>\n<td width=\"133\">Ta\u00adges\u00adbe\u00addarf f\u00fcr Schwangere<\/td>\n<td width=\"113\">Le\u00adbens\u00admit\u00adtel<\/td>\n<td width=\"113\">Kom\u00admen\u00adtar<\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin A (fett\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. \u2013 3. Mo\u00adnate: 700 800 \u00b5g\/Tag\n<p>Ab 4. Mo\u00adnate: 800 \u00b5g\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. But\u00adter, Eier, Feld\u00adsa\u00adlat, Spi\u00adnat, Pa\u00adprika (gelb, rot), Ka\u00adrot\u00adten, in \u00d6l ein\u00adge\u00adleg\u00adter&nbsp;Fisch<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin B1 (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. Tri\u00admes\u00adter: 1,0 mg\/Tag\n<p>2. Tri\u00admes\u00adter: 1,2 mg\/Tag<\/p>\n<p>3. Tri\u00admes\u00adter: 1,3 mg\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. Schwei\u00adne\u00adfleisch, Fisch, Bier\u00adhefe, Wei\u00adzen\u00adkeime, Voll\u00adkorn\u00adpro\u00addukte, N\u00fcsse, Kar\u00adtof\u00adfeln, H\u00fclsenfr\u00fcchte<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin B2 (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. Tri\u00admes\u00adter: 1,1 mg\/Tag\n<p>2. Tri\u00admes\u00adter: 1,3 mg\/Tag<\/p>\n<p>3. Tri\u00admes\u00adter: 1,4 mg\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. Voll\u00adkorn\u00adpro\u00addukte, Wei\u00adzen\u00adkeime, Milch\u00adpro\u00addukte, Fleisch, Eier, Fisch, Bierhefe<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin B6 (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. Tri\u00admes\u00adter: 1,5 mg\/Tag\n<p>2. und 3. Tri\u00admes\u00adter: 1,8 mg\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. Ba\u00adna\u00adnen, Milch\u00adpro\u00addukte, Eier, Bier\u00adhefe, Wei\u00adzen\u00adkeime, Vollkornprodukte<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin B12 (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">4,5 \u00b5g\/Tag<sup>2<\/sup><\/td>\n<td width=\"113\">u.a. Kalb\u2011, Rind\u2011, Schwei\u00adne\u00adfleisch, Fisch, Eier, Milch, K\u00e4se<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin C (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. \u2013 3. Mo\u00adnat: 95 mg\/Tag\n<p>Ab 4. Mo\u00adnate: 105 mg\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. Obst (v.a. Zi\u00adtrus\u00adfr\u00fcchte, Bee\u00adren), Ge\u00adm\u00fcse (v.a. Pa\u00adprika, Kohl, Kar\u00adtof\u00adfeln, Tomaten)<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin D (fett\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">600 IE\/Tag (15 \u00b5g\/Tag)<sup>1<\/sup><\/td>\n<td width=\"113\">u.a. Milch\u00adpro\u00addukte (z.B. voll\u00adfette Milch, But\u00adter) Le\u00adber\u00adfett von Mee\u00adres\u00adfi\u00adschen, Ei\u00adgelb,&nbsp;Sesam<\/td>\n<td width=\"113\">Schwan\u00adge\u00adren und Stil\u00adlen\u00adden wird nach Ab\u00adspra\u00adche mit dem Arzt die Ein\u00adnahme von Vit\u00adamin D\u2011Supplementen emp\u00adfoh\u00adlen.<sup> 1<\/sup><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin E (fett\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">13 mg\/Tag<sup>2<\/sup><\/td>\n<td width=\"113\">u.a. Voll\u00adkorn\u00adpro\u00addukte, N\u00fcsse, Eier, But\u00adter, pflanz\u00adli\u00adche \u00d6le, Blatt\u00adge\u00adm\u00fcse, Brok\u00adkoli, Avo\u00adca\u00addos, Sojaprodukte<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Vit\u00adamin K (fett\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">60 \u00b5g\/Tag<sup>2<\/sup><\/td>\n<td width=\"113\">u.a. Spi\u00adnat, Brok\u00adkoli, Ro\u00adsen\u00adkohl, Rind- und Ge\u00adfl\u00fc\u00adgel\u00adfleisch, Milch\u00adpro\u00addukte, Eier<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Bio\u00adtin (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">40 \u00b5g\/Tag<sup>2<\/sup><\/td>\n<td width=\"113\">u.a. Milch\u00adpro\u00addukte, Bier\u00adhefe, N\u00fcsse, Ei\u00adgelb, Ha\u00adfer\u00adflo\u00adcken, Linsen<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Nia\u00adcin (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">1. Tri\u00admes\u00adter: 12 mg\/Tag\n<p>2. Tri\u00admes\u00adter: 14 mg \/Tag<\/p>\n<p>3. Tri\u00admes\u00adter: 16 mg\/Tag<sup>2<\/sup><\/p><\/td>\n<td width=\"113\">u.a. Ge\u00adfl\u00fc\u00adgel, Fisch, ma\u00adge\u00adres Fleisch, Bier\u00adhefe, gr\u00fc\u00adnes Ge\u00adm\u00fcse, Milch, Voll\u00adkorn\u00adpro\u00addukte, Weizenkeime<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Pan\u00adto\u00adthen\u00ads\u00e4ure (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\">6 mg\/Tag<sup>2<\/sup><\/td>\n<td width=\"113\">u.a. Fisch, Eier, H\u00fcl\u00adsen\u00adfr\u00fcchte, Milch- und Voll\u00adkorn\u00adpro\u00addukte, N\u00fcsse<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Fol\u00ads\u00e4ure (was\u00adser\u00adl\u00f6s\u00adlich)<\/td>\n<td width=\"133\"><\/td>\n<td width=\"113\"><\/td>\n<td width=\"113\">+ 0.4 mg syn\u00adthe\u00adti\u00adsche Fol\u00ads\u00e4ure (drei Mo\u00adnate vor Schwan\u00adger\u00adschafts\u00adbe\u00adginn bis zw\u00f6lf Wo\u00adchen nach ein\u00adge\u00adtre\u00adte\u00adner Schwan\u00adger\u00adschaft)<sup> 1<\/sup><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3>Ausgew\u00e4hlte Mineralien und Spurenelemente<\/h3>\n<table>\n<tbody>\n<tr>\n<td width=\"124\">Ei\u00adsen<\/td>\n<td width=\"132\">30 mg\/Tag<sup>2<\/sup><\/td>\n<td width=\"120\">u.a. ro\u00adtes Fleisch, Fisch, Voll\u00adkorn\u00adpro\u00addukte, Bier\u00adhefe, N\u00fcsse, H\u00fcl\u00adsen\u00adfr\u00fcchte, Ka\u00adrot\u00adten, Avo\u00adcado, Brokkoli<\/td>\n<td width=\"132\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Jod<\/td>\n<td width=\"132\">250 \u00b5g\/Tag<sup>1<\/sup><\/td>\n<td width=\"120\">u.a. Fisch, Feld\u00adsa\u00adlat, Spi\u00adnat, Brok\u00adkoli, Voll\u00adkorn\u00adpro\u00addukte, Kar\u00adtof\u00adfeln, jo\u00addier\u00adtes Speisesalz<\/td>\n<td width=\"132\">Um den er\u00adh\u00f6h\u00adten Jod\u00adbe\u00addarf zu de\u00adcken, sollte auf eine jod\u00adrei\u00adche Er\u00adn\u00e4h\u00adrung ge\u00adach\u00adtet wer\u00adden. Nach R\u00fcck\u00adspra\u00adche mit dem Arzt ist es je nach\u00addem auch rat\u00adsam, ein Jod\u00adsup\u00adple\u00adment ein\u00adzu\u00adneh\u00admen.<sup> 1<\/sup><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Ma\u00adgne\u00adsium<\/td>\n<td width=\"132\">310 mg\/Tag<sup>2<\/sup><\/td>\n<td width=\"120\">u.a. Voll\u00adkorn\u00adpro\u00addukte, H\u00fcl\u00adsen\u00adfr\u00fcchte, Na\u00adtur\u00adreis, N\u00fcsse, Kar\u00adtof\u00adfeln, Brokkoli<\/td>\n<td width=\"132\"><\/td>\n<\/tr>\n<tr>\n<td width=\"124\">Kal\u00adzium<\/td>\n<td width=\"132\">1000 mg\/Tag<sup>2<\/sup><\/td>\n<td width=\"120\">u.a. Kuh\u00admilch, K\u00e4se, Blatt\u00adspi\u00adnat, Brokkoli<\/td>\n<td width=\"132\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><sup>1<\/sup> <a href=\"https:\/\/www.sge-ssn.ch\/grundlagen\/lebensmittel-und-naehrstoffe\/naehrstoffempfehlungen\/empfehlungen-blv\/\">https:\/\/www.sge-ssn.ch\/grundlagen\/lebensmittel-und-naehrstoffe\/naehrstoffempfehlungen\/empfehlungen-blv\/<\/a> <sup>2 <\/sup>DACH Re\u00adfe\u00adrenz\u00adwerte <a href=\"https:\/\/www.sge-ssn.ch\/grundlagen\/lebensmittel-und-naehrstoffe\/naehrstoffempfehlungen\/dachreferenzwerte\/\">https:\/\/www.sge-ssn.ch\/grundlagen\/lebensmittel-und-naehrstoffe\/naehrstoffempfehlungen\/dachreferenzwerte\/<\/a><\/p>\n<p><strong>Wich\u00adti\u00adges zum Schluss<\/strong>: Be\u00adachte, dass die Ein\u00adnahme vie\u00adler N\u00e4hr\u00adstoffe durch eine aus\u00adge\u00adwo\u00adgene Er\u00adn\u00e4h\u00adrung ab\u00adge\u00addeckt wer\u00adden \u2013 mit Aus\u00adnahme ei\u00adni\u00adger Vit\u00adamine (z.B. Fol\u00ads\u00e4ure) und Mi\u00adne\u00adra\u00adlien. Be\u00advor Du Nah\u00adrungs\u00ader\u00adg\u00e4n\u00adzungs\u00admit\u00adtel wie Vit\u00adamin\u00adta\u00adblet\u00adten zu Dir nimmst, kon\u00adsul\u00adtiere bitte Deine Frau\u00aden\u00ad\u00e4rz\u00adtin oder Dei\u00adnen Frau\u00aden\u00adarzt. Denn ohne Man\u00adgel kann die Ein\u00adnahme von Sup\u00adple\u00admen\u00adten auch ne\u00adga\u00adtive Aus\u00adwir\u00adkun\u00adgen auf die Ge\u00adsund\u00adheit des Ba\u00adbys ha\u00adben. Ei\u00adnen Ar\u00adti\u00adkel der S\u00fcd\u00addeut\u00adschen Zei\u00adtung aus dem Jahr 2017 zu Ne\u00adben\u00adwir\u00adkun\u00adgen von Nah\u00adrungs\u00ader\u00adg\u00e4n\u00adzungs\u00admit\u00adteln fin\u00addest Du <a href=\"https:\/\/www.sueddeutsche.de\/gesundheit\/ernaehrung-in-der-schwangerschaft-vorsicht-vitamine-1.3697569\">ici<\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Es gibt wohl we\u00adnige Vit\u00adamine, \u00fcber die zum Thema Schwan\u00adger\u00adschaft mehr dis\u00adku\u00adtiert wird als Fol\u00ads\u00e4ure. Wir ha\u00adben f\u00fcr Dich das Wich\u00adtigste zusammengefasst.<\/p>","protected":false},"author":1,"featured_media":29320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-28995","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ernaehrung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vitamine und Mineralien: Alles, was Du wissen musst - YourHappyBox<\/title>\n<meta name=\"description\" content=\"Wir erkl\u00e4ren die unterschiedlichen Vitamine und Mineralien die w\u00e4hrend der Schwangerschaft von \u00c4rzten und Hebammmen empfohlen sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yourhappybox.ch\/fr\/vitamine-und-mineralien-alles-was-du-wissen-musst\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vitamine und Mineralien: Alles, was Du wissen musst - YourHappyBox\" \/>\n<meta property=\"og:description\" content=\"Wir erkl\u00e4ren die unterschiedlichen Vitamine und Mineralien die w\u00e4hrend der Schwangerschaft von \u00c4rzten und Hebammmen empfohlen sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yourhappybox.ch\/fr\/vitamine-und-mineralien-alles-was-du-wissen-musst\/\" \/>\n<meta property=\"og:site_name\" content=\"YourHappyBox\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-10T14:04:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-23T07:49:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"happyboxgusmoadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"happyboxgusmoadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/\"},\"author\":{\"name\":\"happyboxgusmoadmin\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/#\\\/schema\\\/person\\\/9b40676f91c29282cf073e4fa9bedd20\"},\"headline\":\"Vitamine und Mineralien: Alles, was Du wissen musst\",\"datePublished\":\"2021-11-10T14:04:36+00:00\",\"dateModified\":\"2022-02-23T07:49:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/\"},\"wordCount\":928,\"image\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourhappybox.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg\",\"articleSection\":[\"Ern\u00e4hrung\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/\",\"url\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/\",\"name\":\"Vitamine und Mineralien: Alles, was Du wissen musst - YourHappyBox\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourhappybox.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg\",\"datePublished\":\"2021-11-10T14:04:36+00:00\",\"dateModified\":\"2022-02-23T07:49:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/#\\\/schema\\\/person\\\/9b40676f91c29282cf073e4fa9bedd20\"},\"description\":\"Wir erkl\u00e4ren die unterschiedlichen Vitamine und Mineralien die w\u00e4hrend der Schwangerschaft von \u00c4rzten und Hebammmen empfohlen sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yourhappybox.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/yourhappybox.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"diana-polekhina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/vitamine-und-mineralien-alles-was-du-wissen-musst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/yourhappybox.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vitamine und Mineralien: Alles, was Du wissen musst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/\",\"name\":\"YourHappyBox\",\"description\":\"Die Box, die dir Zeit w\u00e4hrend deiner Schwangerschaft schenkt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yourhappybox.ch\\\/en\\\/#\\\/schema\\\/person\\\/9b40676f91c29282cf073e4fa9bedd20\",\"name\":\"happyboxgusmoadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g\",\"caption\":\"happyboxgusmoadmin\"},\"sameAs\":[\"https:\\\/\\\/yourhappybox.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vit\u00adamine und Mi\u00adne\u00adra\u00adlien: Al\u00adles, was Du wis\u00adsen musst \u2014 YourHappyBox","description":"Wir er\u00adkl\u00e4\u00adren die un\u00adter\u00adschied\u00adli\u00adchen Vit\u00adamine und Mi\u00adne\u00adra\u00adlien die w\u00e4h\u00adrend der Schwan\u00adger\u00adschaft von \u00c4rz\u00adten und Heb\u00adamm\u00admen emp\u00adfoh\u00adlen&nbsp;sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yourhappybox.ch\/fr\/vitamine-und-mineralien-alles-was-du-wissen-musst\/","og_locale":"fr_FR","og_type":"article","og_title":"Vitamine und Mineralien: Alles, was Du wissen musst - YourHappyBox","og_description":"Wir erkl\u00e4ren die unterschiedlichen Vitamine und Mineralien die w\u00e4hrend der Schwangerschaft von \u00c4rzten und Hebammmen empfohlen sind.","og_url":"https:\/\/yourhappybox.ch\/fr\/vitamine-und-mineralien-alles-was-du-wissen-musst\/","og_site_name":"YourHappyBox","article_published_time":"2021-11-10T14:04:36+00:00","article_modified_time":"2022-02-23T07:49:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"happyboxgusmoadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"happyboxgusmoadmin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#article","isPartOf":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/"},"author":{"name":"happyboxgusmoadmin","@id":"https:\/\/yourhappybox.ch\/en\/#\/schema\/person\/9b40676f91c29282cf073e4fa9bedd20"},"headline":"Vitamine und Mineralien: Alles, was Du wissen musst","datePublished":"2021-11-10T14:04:36+00:00","dateModified":"2022-02-23T07:49:26+00:00","mainEntityOfPage":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/"},"wordCount":928,"image":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#primaryimage"},"thumbnailUrl":"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg","articleSection":["Ern\u00e4hrung"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/","url":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/","name":"Vit\u00adamine und Mi\u00adne\u00adra\u00adlien: Al\u00adles, was Du wis\u00adsen musst \u2014 YourHappyBox","isPartOf":{"@id":"https:\/\/yourhappybox.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#primaryimage"},"image":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#primaryimage"},"thumbnailUrl":"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg","datePublished":"2021-11-10T14:04:36+00:00","dateModified":"2022-02-23T07:49:26+00:00","author":{"@id":"https:\/\/yourhappybox.ch\/en\/#\/schema\/person\/9b40676f91c29282cf073e4fa9bedd20"},"description":"Wir er\u00adkl\u00e4\u00adren die un\u00adter\u00adschied\u00adli\u00adchen Vit\u00adamine und Mi\u00adne\u00adra\u00adlien die w\u00e4h\u00adrend der Schwan\u00adger\u00adschaft von \u00c4rz\u00adten und Heb\u00adamm\u00admen emp\u00adfoh\u00adlen&nbsp;sind.","breadcrumb":{"@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#primaryimage","url":"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg","contentUrl":"https:\/\/yourhappybox.ch\/wp-content\/uploads\/2021\/11\/diana-polekhina-GHp78jdvOZY-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"diana-polekhina"},{"@type":"BreadcrumbList","@id":"https:\/\/yourhappybox.ch\/en\/vitamine-und-mineralien-alles-was-du-wissen-musst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/yourhappybox.ch\/"},{"@type":"ListItem","position":2,"name":"Vitamine und Mineralien: Alles, was Du wissen musst"}]},{"@type":"WebSite","@id":"https:\/\/yourhappybox.ch\/en\/#website","url":"https:\/\/yourhappybox.ch\/en\/","name":"Your\u00adHap\u00adpy\u00adBox","description":"Die Box, die dir Zeit w\u00e4h\u00adrend dei\u00adner Schwan\u00adger\u00adschaft schenkt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourhappybox.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/yourhappybox.ch\/en\/#\/schema\/person\/9b40676f91c29282cf073e4fa9bedd20","name":"hap\u00adpy\u00adbox\u00adgus\u00admoad\u00admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3590583bb7e331e865bf830ac267adf957a3b115b328e90c6329f9fb18c3a85?s=96&d=mm&r=g","caption":"happyboxgusmoadmin"},"sameAs":["https:\/\/yourhappybox.ch"]}]}},"_links":{"self":[{"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/posts\/28995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/comments?post=28995"}],"version-history":[{"count":3,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/posts\/28995\/revisions"}],"predecessor-version":[{"id":29002,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/posts\/28995\/revisions\/29002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/media\/29320"}],"wp:attachment":[{"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/media?parent=28995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/categories?post=28995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourhappybox.ch\/fr\/wp-json\/wp\/v2\/tags?post=28995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}